{"id":7402,"date":"2026-06-18T06:43:34","date_gmt":"2026-06-18T06:43:34","guid":{"rendered":"https:\/\/keertek.com\/?post_type=products&#038;p=7402"},"modified":"2026-08-19T09:14:20","modified_gmt":"2026-08-19T09:14:20","slug":"ker-series-intelligent-integrated-ultrasonic-cleaning-system","status":"publish","type":"products","link":"https:\/\/keertek.com\/es\/products\/ker-series-intelligent-integrated-ultrasonic-cleaning-system\/","title":{"rendered":"Sistema de limpieza por ultrasonidos integrado inteligente serie KER"},"content":{"rendered":"<p>La lavadora ultras\u00f3nica de la serie KER es un sistema de limpieza ultras\u00f3nica inteligente e integrado, dise\u00f1ado para limpiar r\u00e1pidamente distintos componentes gracias a su dise\u00f1o avanzado y \u00abtodo en uno\u00bb. Ofrece una interacci\u00f3n \u00f3ptimo entre el usuario y el sistema e incorpora la tecnolog\u00eda de limpieza m\u00e1s eficaz. Su funcionamiento con un solo toque reduce al m\u00ednimo las tareas manuales durante el proceso de limpieza.<\/p>","protected":false},"excerpt":{"rendered":"<p>La lavadora ultras\u00f3nica de la serie KER es un sistema de limpieza ultras\u00f3nica inteligente e integrado, dise\u00f1ado para limpiar r\u00e1pidamente distintos componentes gracias a su dise\u00f1o avanzado y \u00abtodo en uno\u00bb. Ofrece una interacci\u00f3n \u00f3ptimo entre el usuario y el sistema e incorpora la tecnolog\u00eda de limpieza m\u00e1s eficaz. Su funcionamiento con un solo toque reduce al m\u00ednimo las tareas manuales durante el proceso de limpieza.<\/p>","protected":false},"author":6,"featured_media":7407,"template":"","format":"standard","meta":{"_acf_changed":false},"machine-tonnage":[132],"product-categorie":[127],"class_list":["post-7402","products","type-products","status-publish","format-standard","has-post-thumbnail","hentry","machine-tonnage-132","product-categorie-ultrasonic-cleaning-machine-classification"],"acf":[],"_links":{"self":[{"href":"https:\/\/keertek.com\/es\/wp-json\/wp\/v2\/products\/7402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/keertek.com\/es\/wp-json\/wp\/v2\/products"}],"about":[{"href":"https:\/\/keertek.com\/es\/wp-json\/wp\/v2\/types\/products"}],"author":[{"embeddable":true,"href":"https:\/\/keertek.com\/es\/wp-json\/wp\/v2\/users\/6"}],"version-history":[{"count":1,"href":"https:\/\/keertek.com\/es\/wp-json\/wp\/v2\/products\/7402\/revisions"}],"predecessor-version":[{"id":8875,"href":"https:\/\/keertek.com\/es\/wp-json\/wp\/v2\/products\/7402\/revisions\/8875"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/keertek.com\/es\/wp-json\/wp\/v2\/media\/7407"}],"wp:attachment":[{"href":"https:\/\/keertek.com\/es\/wp-json\/wp\/v2\/media?parent=7402"}],"wp:term":[{"taxonomy":"machine-tonnage","embeddable":true,"href":"https:\/\/keertek.com\/es\/wp-json\/wp\/v2\/machine-tonnage?post=7402"},{"taxonomy":"product-categorie","embeddable":true,"href":"https:\/\/keertek.com\/es\/wp-json\/wp\/v2\/product-categorie?post=7402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}